{"id":6620,"date":"2023-09-11T09:32:17","date_gmt":"2023-09-11T07:32:17","guid":{"rendered":"https:\/\/campingcoiroux.fr\/hebergement\/mobilheim-eden-6-personen-klimaanlage\/"},"modified":"2025-11-19T09:24:11","modified_gmt":"2025-11-19T08:24:11","slug":"mobilheim-eden-6-personen-klimaanlage","status":"publish","type":"hebergement","link":"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/","title":{"rendered":"Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers"},"content":{"rendered":"<p>Jahr 2023 &#8211; Fl\u00e4che: 33 m\u00b2<\/p>\n<p>Schlafbereich: ein Schlafzimmer mit 1 Doppelbett, zwei Schlafzimmer mit 2 Einzelbetten nebeneinander, Kissen und Decken vorhanden<\/p>\n<p>Wohn-\/Wohnbereich: ausgestattete K\u00fcche (Sp\u00fcle, Gas, K\u00fchl-\/Gefrierschrank, Kaffeemaschine, Mikrowelle, Geschirr, Geschirrsp\u00fcler), umschaltbare Klimaanlage, Fernseher, Heizung im Wohnzimmer<\/p>\n<p>Sanit\u00e4r: Badezimmer mit Dusche, Waschbecken und separatem WC.<\/p>\n<p>Au\u00dfenbereich: \u00fcberdachte Terrasse mit Gartenm\u00f6beln und 2 Sonnenliegen<\/p>\n<p>Haustiere erlaubt (unter bestimmten Bedingungen).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jahr 2023 &#8211; Fl\u00e4che: 33 m\u00b2 Schlafbereich: ein Schlafzimmer mit 1 Doppelbett, zwei Schlafzimmer mit 2 Einzelbetten nebeneinander, Kissen und Decken vorhanden Wohn-\/Wohnbereich: ausgestattete K\u00fcche (Sp\u00fcle, Gas, K\u00fchl-\/Gefrierschrank, Kaffeemaschine, Mikrowelle, Geschirr, Geschirrsp\u00fcler), umschaltbare Klimaanlage, Fernseher, Heizung im Wohnzimmer Sanit\u00e4r: Badezimmer mit Dusche, Waschbecken und separatem WC. Au\u00dfenbereich: \u00fcberdachte Terrasse mit Gartenm\u00f6beln und 2 Sonnenliegen Haustiere [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","hebergement_type":[200,199],"hebergement_atout":[],"criterion":[185,201,186,187,190],"class_list":["post-6620","hebergement","type-hebergement","status-publish","hentry","hebergement_type-location","hebergement_type-mobil-home","criterion-chauffage-de","criterion-climatisation","criterion-interieur-de","criterion-lave-vaisselle-de","criterion-television-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers - Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers - Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti\" \/>\n<meta property=\"og:description\" content=\"Jahr 2023 &#8211; Fl\u00e4che: 33 m\u00b2 Schlafbereich: ein Schlafzimmer mit 1 Doppelbett, zwei Schlafzimmer mit 2 Einzelbetten nebeneinander, Kissen und Decken vorhanden Wohn-\/Wohnbereich: ausgestattete K\u00fcche (Sp\u00fcle, Gas, K\u00fchl-\/Gefrierschrank, Kaffeemaschine, Mikrowelle, Geschirr, Geschirrsp\u00fcler), umschaltbare Klimaanlage, Fernseher, Heizung im Wohnzimmer Sanit\u00e4r: Badezimmer mit Dusche, Waschbecken und separatem WC. Au\u00dfenbereich: \u00fcberdachte Terrasse mit Gartenm\u00f6beln und 2 Sonnenliegen Haustiere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T08:24:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/\",\"url\":\"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/\",\"name\":\"Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers - Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti\",\"isPartOf\":{\"@id\":\"https:\/\/campingcoiroux.fr\/de\/#website\"},\"datePublished\":\"2023-09-11T07:32:17+00:00\",\"dateModified\":\"2025-11-19T08:24:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/campingcoiroux.fr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/campingcoiroux.fr\/de\/#website\",\"url\":\"https:\/\/campingcoiroux.fr\/de\/\",\"name\":\"Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/campingcoiroux.fr\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/campingcoiroux.fr\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/campingcoiroux.fr\/de\/#organization\",\"name\":\"Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti\",\"url\":\"https:\/\/campingcoiroux.fr\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/campingcoiroux.fr\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/campingcoiroux.fr\/wp-content\/uploads\/sites\/27\/2023\/08\/logo-coiroux.png\",\"contentUrl\":\"https:\/\/campingcoiroux.fr\/wp-content\/uploads\/sites\/27\/2023\/08\/logo-coiroux.png\",\"width\":2048,\"height\":1260,\"caption\":\"Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti\"},\"image\":{\"@id\":\"https:\/\/campingcoiroux.fr\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers - Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers - Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti","og_description":"Jahr 2023 &#8211; Fl\u00e4che: 33 m\u00b2 Schlafbereich: ein Schlafzimmer mit 1 Doppelbett, zwei Schlafzimmer mit 2 Einzelbetten nebeneinander, Kissen und Decken vorhanden Wohn-\/Wohnbereich: ausgestattete K\u00fcche (Sp\u00fcle, Gas, K\u00fchl-\/Gefrierschrank, Kaffeemaschine, Mikrowelle, Geschirr, Geschirrsp\u00fcler), umschaltbare Klimaanlage, Fernseher, Heizung im Wohnzimmer Sanit\u00e4r: Badezimmer mit Dusche, Waschbecken und separatem WC. Au\u00dfenbereich: \u00fcberdachte Terrasse mit Gartenm\u00f6beln und 2 Sonnenliegen Haustiere [&hellip;]","og_url":"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/","og_site_name":"Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti","article_modified_time":"2025-11-19T08:24:11+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/","url":"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/","name":"Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers - Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti","isPartOf":{"@id":"https:\/\/campingcoiroux.fr\/de\/#website"},"datePublished":"2023-09-11T07:32:17+00:00","dateModified":"2025-11-19T08:24:11+00:00","breadcrumb":{"@id":"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/campingcoiroux.fr\/de\/unterkunft\/mobilheim-eden-6-personen-klimaanlage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/campingcoiroux.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Premium-Mobilheim 3 Schlafzimmern f\u00fcr 6 Pers"}]},{"@type":"WebSite","@id":"https:\/\/campingcoiroux.fr\/de\/#website","url":"https:\/\/campingcoiroux.fr\/de\/","name":"Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti","description":"","publisher":{"@id":"https:\/\/campingcoiroux.fr\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campingcoiroux.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/campingcoiroux.fr\/de\/#organization","name":"Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti","url":"https:\/\/campingcoiroux.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/campingcoiroux.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/campingcoiroux.fr\/wp-content\/uploads\/sites\/27\/2023\/08\/logo-coiroux.png","contentUrl":"https:\/\/campingcoiroux.fr\/wp-content\/uploads\/sites\/27\/2023\/08\/logo-coiroux.png","width":2048,"height":1260,"caption":"Camping Paradis Le Coiroux - Site Officiel - Meilleur Prix Garanti"},"image":{"@id":"https:\/\/campingcoiroux.fr\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/hebergement\/6620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"version-history":[{"count":5,"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/hebergement\/6620\/revisions"}],"predecessor-version":[{"id":11351,"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/hebergement\/6620\/revisions\/11351"}],"wp:attachment":[{"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/media?parent=6620"}],"wp:term":[{"taxonomy":"hebergement_type","embeddable":true,"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/hebergement_type?post=6620"},{"taxonomy":"hebergement_atout","embeddable":true,"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/hebergement_atout?post=6620"},{"taxonomy":"criterion","embeddable":true,"href":"https:\/\/campingcoiroux.fr\/de\/wp-json\/wp\/v2\/criterion?post=6620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}